{"id":83,"date":"2025-12-02T22:31:11","date_gmt":"2025-12-02T22:31:11","guid":{"rendered":"https:\/\/navedigital.cl\/mot\/producto\/set-de-3-dados-30-cm-x-30-cm-x-30-cm\/"},"modified":"2025-12-04T14:22:45","modified_gmt":"2025-12-04T17:22:45","slug":"set-de-3-dados-30-cm-x-30-cm-x-30-cm","status":"publish","type":"product","link":"https:\/\/navedigital.cl\/mot\/producto\/set-de-3-dados-30-cm-x-30-cm-x-30-cm\/","title":{"rendered":"Set de 3 Dados (30 cm x 30 cm x 30 cm)"},"content":{"rendered":"<p>Los ni\u00f1os se deleitar\u00e1n con nuestros dados, ya que ofrecen a los m\u00e1s peque\u00f1os momentos de inspiraci\u00f3n y diversi\u00f3n en un entorno \u00fanico. Esta innovadora herramienta lo ayudar\u00e1 a relajarse y desarrollar su creatividad y explorar su imaginaci\u00f3n. Todo en un solo juego, entretenidos dados de m\u00faltiples modelos, \u00fatiles para desarrollar la motricidad gruesa de los ni\u00f1os. Incluyendo casas, fiestas de cumplea\u00f1os, educaci\u00f3n primaria, restaurantes, centros de salud, etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Material lavable. Espuma alta densidad 25. Tela: PU. Cierre de la mejor calidad N\u00b0 5.<\/p>\n","protected":false},"featured_media":143,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[71,70],"product_tag":[],"class_list":["post-83","product","type-product","status-publish","has-post-thumbnail","product_cat-dados-de-aprendizage","product_cat-psicomotricidad","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product\/83\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/media\/143"}],"wp:attachment":[{"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product_brand?post=83"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product_cat?post=83"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/navedigital.cl\/mot\/wp-json\/wp\/v2\/product_tag?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}